{"id":11047,"date":"2026-09-02T09:11:14","date_gmt":"2026-09-02T13:11:14","guid":{"rendered":"https:\/\/ambottawa.esteri.it\/?p=11047"},"modified":"2026-09-02T09:13:37","modified_gmt":"2026-09-02T13:13:37","slug":"litalie-et-le-canada-renforcent-leur-cooperation-dans-le-domaine-des-technologies-quantiques","status":"publish","type":"post","link":"https:\/\/ambottawa.esteri.it\/fr\/news\/dall_ambasciata\/2026\/09\/litalie-et-le-canada-renforcent-leur-cooperation-dans-le-domaine-des-technologies-quantiques\/","title":{"rendered":"L\u2019Italie et le Canada renforcent leur coop\u00e9ration dans le domaine des technologies quantiques"},"content":{"rendered":"<p class=\"isSelectedEnd\">Le s\u00e9minaire \u00ab Building Quantum Bridges: Italy\u2013Canada Partnership for the Quantum Future \u00bb, organis\u00e9 par le Bureau scientifique de l\u2019Ambassade d\u2019Italie au Canada et accueilli par l\u2019Institut culturel italien de Toronto, s\u2019est tenu hier \u00e0 Toronto.<\/p>\n<p class=\"isSelectedEnd\">L\u2019initiative s\u2019est d\u00e9roul\u00e9e \u00e0 l\u2019occasion de la signature de deux protocoles d\u2019entente. Le premier a \u00e9t\u00e9 conclu entre le Centre for Quantum Information and Quantum Control (CQIQC) et trois des principaux organismes italiens de recherche : l\u2019Institut national de physique nucl\u00e9aire (INFN), le Conseil national de la recherche d\u2019Italie (CNR) et l\u2019Agence nationale italienne pour les nouvelles technologies, l\u2019\u00e9nergie et le d\u00e9veloppement \u00e9conomique durable (ENEA). Le second a \u00e9t\u00e9 conclu entre ces m\u00eames organismes italiens de recherche, le Perimeter Institute for Theoretical Physics et l\u2019Institute for Quantum Computing de l\u2019Universit\u00e9 de Waterloo.<\/p>\n<p class=\"isSelectedEnd\">Ces deux ententes jettent les bases d\u2019un renforcement et d\u2019une structuration accrue de la coop\u00e9ration bilat\u00e9rale dans le domaine des technologies quantiques, en favorisant des initiatives scientifiques conjointes, les \u00e9changes entre chercheurs et de nouvelles synergies entre les \u00e9cosyst\u00e8mes de recherche italien et canadien.<\/p>\n<p class=\"isSelectedEnd\">La rencontre scientifique a r\u00e9uni des repr\u00e9sentants des milieux scientifique et universitaire italiens et canadiens, offrant une occasion d\u2019\u00e9changer sur leurs expertises respectives dans le domaine quantique ainsi que sur les domaines de collaboration possibles, de la recherche fondamentale au d\u00e9veloppement de nouvelles technologies et applications.<\/p>\n<p>Parmi les participants figuraient le Consul g\u00e9n\u00e9ral d\u2019Italie \u00e0 Toronto, Andrea Bertozzi, Janice Vogtle, directrice r\u00e9gionale pour l\u2019Ontario \u00e0 Affaires mondiales Canada, ainsi que, pour la d\u00e9l\u00e9gation italienne, le pr\u00e9sident de l\u2019INFN, le professeur Antonio Zoccoli, M. Luigi De Dominicis (ENEA) et M. Stefano Fabris (CNR).<\/p>\n","protected":false},"excerpt":{"rendered":"Le s\u00e9minaire \u00ab Building Quantum Bridges: Italy\u2013Canada Partnership for the Quantum Future \u00bb, organis\u00e9 par le Bureau scientifique de l\u2019Ambassade d\u2019Italie au Canada et accueilli par l\u2019Institut culturel italien de Toronto, s\u2019est tenu hier \u00e0 Toronto. L\u2019initiative s\u2019est d\u00e9roul\u00e9e \u00e0 l\u2019occasion de la signature de deux protocoles d\u2019entente. Le premier a \u00e9t\u00e9 conclu entre le [&hellip;]","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-11047","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/ambottawa.esteri.it\/fr\/wp-json\/wp\/v2\/posts\/11047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ambottawa.esteri.it\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ambottawa.esteri.it\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ambottawa.esteri.it\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/ambottawa.esteri.it\/fr\/wp-json\/wp\/v2\/comments?post=11047"}],"version-history":[{"count":1,"href":"https:\/\/ambottawa.esteri.it\/fr\/wp-json\/wp\/v2\/posts\/11047\/revisions"}],"predecessor-version":[{"id":11050,"href":"https:\/\/ambottawa.esteri.it\/fr\/wp-json\/wp\/v2\/posts\/11047\/revisions\/11050"}],"wp:attachment":[{"href":"https:\/\/ambottawa.esteri.it\/fr\/wp-json\/wp\/v2\/media?parent=11047"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ambottawa.esteri.it\/fr\/wp-json\/wp\/v2\/tags?post=11047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}